{"id":11178,"date":"2025-09-23T08:21:32","date_gmt":"2025-09-23T08:21:32","guid":{"rendered":"https:\/\/www.sprich.ch\/statico\/"},"modified":"2025-12-10T12:32:17","modified_gmt":"2025-12-10T12:32:17","slug":"statico","status":"publish","type":"page","link":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico","title":{"rendered":"Statico"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11178\" class=\"elementor elementor-11178 elementor-704\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f427bb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6f427bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cf0bf7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"8cf0bf7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86904f6 elementor-widget elementor-widget-spacer\" data-id=\"86904f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8aca970 elementor-widget elementor-widget-heading\" data-id=\"8aca970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">STATICO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9df8e63 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9df8e63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa9583 elementor-widget elementor-widget-text-editor\" data-id=\"3fa9583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Il programma statico calcola il carico dei grigliati in accordo ai valori RAL, SIA e SPRICH. Il programma \u00e8 stato progettato e realizzato nell\u2019arco di pi\u00f9 mesi, in collaborazione con la\u00a0<a href=\"https:\/\/www.hslu.ch\/de-ch\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scuola universitaria professionale di Lucerna<\/a>\u00a0(SUPL).<\/p>\n<p>Nel programma statico sono stati integrati tutti i valori scientificamente approvati, per permettere rapidi calcoli sulla scorta di norme europee e svizzere. SPRICH pu\u00f2 cos\u00ec ora fornire ai clienti una consulenza relativa ai carichi dei grigliati pressati e fornire certificati per i valori Fv (carico utile) e Fp (carico puntuale), secondo i valori SIA, RAL e SPRICH. Attualmente i calcoli sono possibili per acciaio, acciaio inossidabile e alluminio in diverse leghe.<\/p>\n<p>Per effettuare i calcoli necessari per altri certificati della nostra gamma prodotti, come gradini per scale, griglie in lamiera profilata, griglie in PRFV ecc. la collaborazione con la SPUL prosegue in un\u2019ulteriore fase. Nell\u2019imminente fase operativa il progetto, fino ad ora assolutamente unico in Svizzera, sar\u00e0 supportato da\u00a0<a href=\"https:\/\/www.innosuisse.ch\/inno\/de\/home.html\" target=\"_blank\" rel=\"noopener noreferrer\">Innosuisse<\/a>, l\u2019agenzia svizzera per la promozione dell\u2019innovazione.<\/p>\n<p>Per il vostro progetto avete necessit\u00e0 di calcolare i carichi in accordo a RAL\/SIA? Contattateci al numero <a href=\"tel:+41 41 768 10 90\">+41 41 768 10 90<\/a> o via e-mail all\u2019indirizzo\u00a0<a href=\"mailto:vendita@sprich.ch\">vendita@sprich.ch<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d7da7 elementor-widget elementor-widget-spacer\" data-id=\"f5d7da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af2a0e1 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"af2a0e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-510db18 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"510db18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6d9824 elementor-widget elementor-widget-image\" data-id=\"b6d9824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"580\" height=\"423\" src=\"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025.webp\" class=\"attachment-large size-large wp-image-9607\" alt=\"sprich_zertifikat-statik_2025\" srcset=\"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025.webp 580w, https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025-300x219.webp 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-197f85c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"197f85c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d15473a elementor-widget elementor-widget-heading\" data-id=\"d15473a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CALCOLO ESEMPLIFICATIVO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7c0056 elementor-widget elementor-widget-text-editor\" data-id=\"e7c0056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<header>\n<h5 class=\"\">Carico puntuale del grigliato pressato<\/h5>\n<\/header>\n<p><\/p>\n<div class=\"ce-textpic ce-right ce-intext\">\n<div class=\"ce-bodytext\">\n<ul>\n<li>S235<\/li>\n<li>Barre trasversale: 30\/2 mm<\/li>\n<li>Maglia: 22&#215;22 mm<\/li>\n<li>Lunghezza x larghezza: 1200&#215;750 mm con 1.5kN<\/li>\n<\/ul>\n<\/div>\n<p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d9e27e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6d9e27e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f78fa7f e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f78fa7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2388437 elementor-widget elementor-widget-image\" data-id=\"2388437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"462\" src=\"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik-2_2025.webp\" class=\"attachment-large size-large wp-image-9608\" alt=\"sprich_zertifikat-statik-2_2025\" srcset=\"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik-2_2025.webp 580w, https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik-2_2025-300x239.webp 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2b8fcc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b2b8fcc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8662162 elementor-widget elementor-widget-heading\" data-id=\"8662162\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DISPOSIZIONI DEI CARICHI DEL CALCOLO ESEMPLIFICATIVO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-503b8ac elementor-widget elementor-widget-text-editor\" data-id=\"503b8ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le conversioni manuali del carico tramite le relative tabelle sono un ricordo del passato. I collaboratori SPRICH possono avvalersi di una soluzione di conversione che permette di calcolare rapidamente e in tutta sicurezza i carichi ammessi per Fv e Fp secondo RAL e SIA e\/o per diversi materiali.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57f5880 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"57f5880\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4f0f319 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4f0f319\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a46eb57 elementor-widget elementor-widget-image\" data-id=\"a46eb57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"815\" src=\"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik-3_2025.webp\" class=\"attachment-large size-large wp-image-9609\" alt=\"sprich_zertifikat-statik-3_2025\" srcset=\"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik-3_2025.webp 580w, https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik-3_2025-213x300.webp 213w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d362007 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d362007\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9cdf11d elementor-widget elementor-widget-heading\" data-id=\"9cdf11d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CERTIFICATO DEL CALCOLO ESEMPLIFICATIVO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89da6d8 elementor-widget elementor-widget-text-editor\" data-id=\"89da6d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Naturalmente, dopo aver effettuato il calcolo vi forniremo un certificato in accordo ai valori RAL\/SIA o SPRICH.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-901de71 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"901de71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd0a9d1 elementor-widget elementor-widget-spacer\" data-id=\"bd0a9d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>STATICO Il programma statico calcola il carico dei grigliati in accordo ai valori RAL, SIA e SPRICH. Il programma \u00e8 stato progettato e realizzato nell\u2019arco di pi\u00f9 mesi, in collaborazione con la\u00a0Scuola universitaria professionale di Lucerna\u00a0(SUPL). Nel programma statico sono stati integrati tutti i valori scientificamente approvati, per permettere rapidi calcoli sulla scorta di norme europee e svizzere. SPRICH pu\u00f2 cos\u00ec ora fornire ai clienti una consulenza relativa ai carichi dei grigliati pressati e fornire certificati per i valori Fv (carico utile) e Fp (carico puntuale), secondo i valori SIA, RAL e SPRICH. Attualmente i calcoli sono possibili per acciaio, acciaio inossidabile e alluminio in diverse leghe. Per effettuare i calcoli necessari per altri certificati della nostra gamma prodotti, come gradini per scale, griglie in lamiera profilata, griglie in PRFV ecc. la collaborazione con la SPUL prosegue in un\u2019ulteriore fase. Nell\u2019imminente fase operativa il progetto, fino ad ora assolutamente unico in Svizzera, sar\u00e0 supportato da\u00a0Innosuisse, l\u2019agenzia svizzera per la promozione dell\u2019innovazione. Per il vostro progetto avete necessit\u00e0 di calcolare i carichi in accordo a RAL\/SIA? Contattateci al numero +41 41 768 10 90 o via e-mail all\u2019indirizzo\u00a0vendita@sprich.ch. CALCOLO ESEMPLIFICATIVO Carico puntuale del grigliato pressato S235 Barre trasversale: 30\/2 mm Maglia: 22&#215;22 mm Lunghezza x larghezza: 1200&#215;750 mm con 1.5kN DISPOSIZIONI DEI CARICHI DEL CALCOLO ESEMPLIFICATIVO Le conversioni manuali del carico tramite le relative tabelle sono un ricordo del passato. I collaboratori SPRICH possono avvalersi di una soluzione di conversione che permette di calcolare rapidamente e in tutta sicurezza i carichi ammessi per Fv e Fp secondo RAL e SIA e\/o per diversi materiali. CERTIFICATO DEL CALCOLO ESEMPLIFICATIVO Naturalmente, dopo aver effettuato il calcolo vi forniremo un certificato in accordo ai valori RAL\/SIA o SPRICH.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8298,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-11178","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Statico - SPRICH<\/title>\n<meta name=\"description\" content=\"Statik-Service von SPRICH: Belastung berechnen nach RAL\/SIA \u2013 Gitterroste, Treppen, Leitern. Zertifizierte Nachweise inklusive.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Statico\" \/>\n<meta property=\"og:description\" content=\"Statik-Service von SPRICH: Belastung berechnen nach RAL\/SIA \u2013 Gitterroste, Treppen, Leitern. Zertifizierte Nachweise inklusive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico\" \/>\n<meta property=\"og:site_name\" content=\"SPRICH\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T12:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico\",\"url\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico\",\"name\":\"Statico - SPRICH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sprich.ch\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/sprich_zertifikat-statik_2025.webp\",\"datePublished\":\"2025-09-23T08:21:32+00:00\",\"dateModified\":\"2025-12-10T12:32:17+00:00\",\"description\":\"Statik-Service von SPRICH: Belastung berechnen nach RAL\\\/SIA \u2013 Gitterroste, Treppen, Leitern. Zertifizierte Nachweise inklusive.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico#primaryimage\",\"url\":\"https:\\\/\\\/www.sprich.ch\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/sprich_zertifikat-statik_2025.webp\",\"contentUrl\":\"https:\\\/\\\/www.sprich.ch\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/sprich_zertifikat-statik_2025.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/i-nostri-servizi\\\/statico#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sprich.ch\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I nostri servizi\",\"item\":\"https:\\\/\\\/www.sprich.ch\\\/it\\\/unsere-leistungen\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Statico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it#website\",\"url\":\"https:\\\/\\\/www.sprich.ch\\\/it\",\"name\":\"SPRICH\",\"description\":\"Gitterroste, Leitern, Treppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sprich.ch\\\/it?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it#organization\",\"name\":\"SPRICH\",\"url\":\"https:\\\/\\\/www.sprich.ch\\\/it\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sprich.ch\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Sprich_Logo_rgb_pos_quer_600dpi-1-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.sprich.ch\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Sprich_Logo_rgb_pos_quer_600dpi-1-scaled.png\",\"width\":2560,\"height\":695,\"caption\":\"SPRICH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sprich.ch\\\/it#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Statico - SPRICH","description":"Statik-Service von SPRICH: Belastung berechnen nach RAL\/SIA \u2013 Gitterroste, Treppen, Leitern. Zertifizierte Nachweise inklusive.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico","og_locale":"it_IT","og_type":"article","og_title":"Statico","og_description":"Statik-Service von SPRICH: Belastung berechnen nach RAL\/SIA \u2013 Gitterroste, Treppen, Leitern. Zertifizierte Nachweise inklusive.","og_url":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico","og_site_name":"SPRICH","article_modified_time":"2025-12-10T12:32:17+00:00","og_image":[{"width":580,"height":423,"url":"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico","url":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico","name":"Statico - SPRICH","isPartOf":{"@id":"https:\/\/www.sprich.ch\/it#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico#primaryimage"},"image":{"@id":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico#primaryimage"},"thumbnailUrl":"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025.webp","datePublished":"2025-09-23T08:21:32+00:00","dateModified":"2025-12-10T12:32:17+00:00","description":"Statik-Service von SPRICH: Belastung berechnen nach RAL\/SIA \u2013 Gitterroste, Treppen, Leitern. Zertifizierte Nachweise inklusive.","breadcrumb":{"@id":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico#primaryimage","url":"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025.webp","contentUrl":"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/sprich_zertifikat-statik_2025.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sprich.ch\/it\/i-nostri-servizi\/statico#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sprich.ch\/it"},{"@type":"ListItem","position":2,"name":"I nostri servizi","item":"https:\/\/www.sprich.ch\/it\/unsere-leistungen"},{"@type":"ListItem","position":3,"name":"Statico"}]},{"@type":"WebSite","@id":"https:\/\/www.sprich.ch\/it#website","url":"https:\/\/www.sprich.ch\/it","name":"SPRICH","description":"Gitterroste, Leitern, Treppen","publisher":{"@id":"https:\/\/www.sprich.ch\/it#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sprich.ch\/it?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.sprich.ch\/it#organization","name":"SPRICH","url":"https:\/\/www.sprich.ch\/it","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sprich.ch\/it#\/schema\/logo\/image\/","url":"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/Sprich_Logo_rgb_pos_quer_600dpi-1-scaled.png","contentUrl":"https:\/\/www.sprich.ch\/wp-content\/uploads\/2025\/09\/Sprich_Logo_rgb_pos_quer_600dpi-1-scaled.png","width":2560,"height":695,"caption":"SPRICH"},"image":{"@id":"https:\/\/www.sprich.ch\/it#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/pages\/11178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/comments?post=11178"}],"version-history":[{"count":8,"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/pages\/11178\/revisions"}],"predecessor-version":[{"id":20100,"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/pages\/11178\/revisions\/20100"}],"up":[{"embeddable":true,"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/pages\/8298"}],"wp:attachment":[{"href":"https:\/\/www.sprich.ch\/it\/wp-json\/wp\/v2\/media?parent=11178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}